{"id":1082,"date":"2012-11-12T09:35:18","date_gmt":"2012-11-12T09:35:18","guid":{"rendered":"http:\/\/logronopasion.com\/portal\/?p=1082"},"modified":"2012-11-26T18:55:14","modified_gmt":"2012-11-26T18:55:14","slug":"san-millan-de-la-cogolla","status":"publish","type":"post","link":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/","title":{"rendered":"San Millan de la Cogolla"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"center\"><span style=\"text-decoration: underline;\"><strong><em>SAN MILL\u00c1N DE LA COGOLLA<\/em><\/strong><\/span><\/p>\n<p>La Iglesia conmemora hoy 12 de noviembre, la festividad de San Mill\u00e1n, santo totalmente relacionado con nuestra tierra y nuestra Di\u00f3cesis.\u00a0Hemos\u00a0encontrado este gran trabajo de D. Nicol\u00e1s Gonz\u00e1lez Ru\u00edz, donde queda bien detallada y comprobada, la vida de nuestro santo, y los trayectos efectuados durante su larga vida.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1190\" title=\"cruzSanmillan\" src=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png\" alt=\"\" width=\"171\" height=\"166\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Para contar sencillamente la vida de San Mill\u00e1n disponemos de un testimonio fidedigno, sin que esto quiera decir que no deba somet\u00e9rsele por ello al an\u00e1lisis de la cr\u00edtica hist\u00f3rica. San Braulio, obispo de Zaragoza, nos leg\u00f3 un op\u00fasculo latino en el que relata la vida de San Mill\u00e1n. No s\u00f3lo el prestigio del propio narrador ha de impon\u00e9rsenos en este caso. Escribe a poca distancia de los hechos, \u00abporque los venerables sacerdotes de las iglesias de Cristo. Citonato, Sofronio y Geroncio, presb\u00edteros de santa y pur\u00edsima vida, a quienes no dala Iglesiapoco cr\u00e9dito, nos contaron fielmente lo que vieron\u00bb. A estos tres hay que agregar el testimonio \u00abde la muy religiosa Potamia, de santa memoria\u00bb. En la declaraci\u00f3n de cuatro testigos respetables funda San Braulio la biograf\u00eda de San Mill\u00e1n. De su narraci\u00f3n difiere muy poco, siglos adelante, Gonzalo de Berceo, que en realidad traduce libremente al obispo de Zaragoza, dando una versi\u00f3n de nombres de lugares terminante y clara, por simple incorporaci\u00f3n de lo que se admit\u00eda sin vacilar en su momento.<\/p>\n<p style=\"text-align: justify;\">Como en esta localizaci\u00f3n residen algunos de los problemas hist\u00f3ricos que se han discutido en torno de la vida de San Mill\u00e1n, optamos por narrar \u00e9sta primero, siguiendo a San Braulio y respetando la nomenclatura que \u00e9l emplea. Y una vez recogido este fundamental testimonio, del que arranca todo lo que se ha escrito sobre San Mill\u00e1n, trataremos de esclarecer aquellos puntos hist\u00f3ricos aludidos. Parece esto m\u00e1s hacedero y f\u00e1cil de seguir por el lector que plantear a cada cita del nombre de un pueblo, de un castillo o de una monta\u00f1a en el texto de San Braulio el problema de interpretaci\u00f3n correspondiente.<\/p>\n<p style=\"text-align: justify;\">Estamos en el siglo VI de la era cristiana y, con toda seguridad, en el primitivo territorio de la di\u00f3cesis de Tarazona. Espa\u00f1a est\u00e1 dominada por los visigodos, es cat\u00f3lica, y al final de la centuria lo ser\u00e1 solemnemente en la persona de Recaredo. El rinc\u00f3n dela Riojapor donde el Ebro penetra desde Cantabria es el escenario de la vida de San Mill\u00e1n. Las discusiones, que veremos despu\u00e9s, acerca del lugar del nacimiento del Santo no afectan al seguro hecho hist\u00f3rico de su largu\u00edsima permanencia en La Rioja.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Hab\u00eda \u00aben aquel tiempo\u00bb, pues no puede fijarse m\u00e1s que la \u00e9poca y no el a\u00f1o del nacimiento de San Mill\u00e1n, un pastor de ovejas como de veinte a\u00f1os, mancebo ejemplar y temeroso de Dios, que, entretenido en la guarda de su ganado en el mismo coraz\u00f3n de los montes, se acompa\u00f1aba, como era costumbre pastoril, con una c\u00edtara, tratando de evitar as\u00ed el mortal decaimiento del \u00e1nimo, fruto de una prolongada y honda soledad. Un d\u00eda, a este pastor, llamado Mill\u00e1n (esto es, Emiliano; <em>Aemiliani, <\/em>dice el texto latino de San Braulio), \u00able vino un sue\u00f1o del cielo\u00bb, y se le despert\u00f3 el alma con tanto \u00edmpetu y con tan viva luz que determin\u00f3 consagrarse, de todo en todo, a la vida sobrenatural, y parti\u00f3 en busca de las soledades del yermo, donde hacer vida de contemplaci\u00f3n y santificaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El lugar donde naci\u00f3 Mill\u00e1n, el pastor, se llamaba Vergegio, y cercanos a \u00e9l se hallaban los montes y prados donde apacentaba el ganado. Al adoptar la determinaci\u00f3n de consagrarse a la vida religiosa, Mill\u00e1n comprendi\u00f3 que no pod\u00eda hacerlo sin someterse a la debida instrucci\u00f3n y gu\u00eda, y para ello se dirigi\u00f3 a Bilibio, donde en un famoso castillo que guardaba una garganta del Ebro con tal fortaleza y eficacia que jam\u00e1s los sarracenos se atrevieron con \u00e9l, habitaba un monje llamado Felices, que gozaba fama de var\u00f3n sant\u00edsimo. A \u00e9l se dirigi\u00f3 Mill\u00e1n, implor\u00f3 y obtuvo su magisterio, y sujet\u00e1ndose a la severa disciplina que Felices le impuso, se abri\u00f3 las puertas de la vida que deseaba emprender.<\/p>\n<p style=\"text-align: justify;\">Fortalecido con esta ense\u00f1anza, provisto a la vez de reglas y de doctrina, Mill\u00e1n escogi\u00f3 un lugar pr\u00f3ximo a Vergegio para vivir en soledad y oraci\u00f3n, pero no le fue posible permanecer en \u00e9l largo tiempo, porque entre sus convecinos y otros comarcanos corri\u00f3 la fama de su santidad y conflu\u00edan en masa a pedirle consejo y remedio. Deseoso entonces de asegurar la soledad que buscaba para su perfecci\u00f3n, adentr\u00e1ndose por la monta\u00f1a, caminando hacia lo m\u00e1s elevado, intrincado y boscoso de ella, hasta llegar a lo m\u00e1s escondido del Distercio, que tal era el monte en el cual se encontraba. All\u00ed, privado de toda compa\u00f1\u00eda humana, expuesto a la dura inclemencia de nieves y huracanes, permaneci\u00f3 por espacio de cuarenta a\u00f1os, sostenido su cuerpo por las hierbas y frutos silvestres y el agua de los arroyos, y m\u00e1s que nada, por el temple del alma, entregada a Dios.<\/p>\n<p style=\"text-align: justify;\">De este largu\u00edsimo plazo de vida en el yermo que dan como cierto los testimonios recogidos por San Braulio, tal vez no deba dudarse si se piensa que cupo ampliamente en la existencia de San Mill\u00e1n, el cual permaneci\u00f3 en este mundo por espacio de ciento un a\u00f1os. En cuanto a que lograse subsistir en las condiciones que implica un clima despiadado, hemos de pensar en el favor de Dios y en que, si sometido a tales condiciones logra alguien vivir cuatro a\u00f1os, puede, sin duda alguna, vivir los cuarenta. De las luchas y sacrificios de esta \u00e9poca, de las tentaciones que sufri\u00f3, de las asechanzas a las que el demonio le sometiese, dice con gran acierto San Braulio que \u00abs\u00f3lo pueden conocerlo bien aquellos que, consagr\u00e1ndose a la virtud, lo experimentan en s\u00ed mismos\u00bb.<\/p>\n<p style=\"text-align: justify;\">El selv\u00e1tico aislamiento en el que Mill\u00e1n permanec\u00eda no fue obst\u00e1culo para que hasta \u00e9l llegase alg\u00fan peregrino y para que por el contorno se difundiese la fama de una santidad en la que cre\u00edan todos. Esta fama, corriendo de boca en boca, fue a parar hasta los o\u00eddos de Didimo, por aquel entonces obispo de Tarazona. Teniendo jurisdicci\u00f3n sobre el \u00e1spero eremita por hallarse el lugar que hab\u00eda elegido para la oraci\u00f3n en territorio de su di\u00f3cesis, el obispo le envi\u00f3 mensaje para que se presentara a recibir las sagradas \u00f3rdenes, pues deseaba que como sacerdote, y no como monje del yermo, diese pruebas de su activa virtud.<\/p>\n<p style=\"text-align: justify;\">No se cre\u00eda Mill\u00e1n apto para el desempe\u00f1o de las tareas sacerdotales, al punto que dicen que al recibir el primer mensaje del obispo abrig\u00f3 la idea de huirse m\u00e1s all\u00e1 de los l\u00edmites de la di\u00f3cesis de Tarazona. Pero al fin pens\u00f3 que deb\u00eda obedecer y, una vez ordenado, se le confiri\u00f3 la parroquia de Vergegio, su pueblo natal. All\u00ed prosigui\u00f3 su ejemplar vida de privaciones y sacrificios, entreg\u00e1ndose a dilatados ayunos y severas mortificaciones. Se afirma que siendo escas\u00edsimas sus letras, como era natural, pues no tuvo otra instrucci\u00f3n que la que le comunicara el monje Felices, los a\u00f1os de vida erem\u00edtica le hab\u00edan proporcionado una sabidur\u00eda profunda, fruto de las meditaciones en la monta\u00f1a, a solas con Dios.<\/p>\n<p style=\"text-align: justify;\">Con todo, la etapa de San Mill\u00e1n como p\u00e1rroco de Vergegio hab\u00eda de terminar mal. Se propuso el Santo desterrar todo h\u00e1bito de codicia en la casa del Se\u00f1or y proclam\u00f3 que la mejor administraci\u00f3n posible de los bienes eclesi\u00e1sticos era repartirlos entre los pobres. As\u00ed se lo propuso y as\u00ed lo realiz\u00f3 en Vergegio, con gran esc\u00e1ndalo de los otros cl\u00e9rigos, que, hechos al disfrute de diezmos y primicias, acabaron por querellarse ante el obispo Didimo, acusando a San Mill\u00e1n de malversaci\u00f3n por el grave perjuicio que infer\u00eda a los bienes dela Iglesia. AfirmaSan Braulio que el prelado se sent\u00eda envidioso del gran predicamento alcanzado por las excelsas virtudes que todos reconoc\u00edan en San Mill\u00e1n, y dio o\u00eddos a la denuncia, ardi\u00f3 en c\u00f3lera, increp\u00f3 al Santo y le priv\u00f3 del curato que \u00e9l mismo se hab\u00eda obstinado en concederle. San Mill\u00e1n sufri\u00f3 los reproches con tranquila y humilde paciencia y se retir\u00f3 al lugar que se conoce como su oratorio para continuar su vida de oraci\u00f3n y penitencia.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n veremos lo que la investigaci\u00f3n hist\u00f3rica ha podido agregar al sencillo relato de San Braulio. Despu\u00e9s de aludir a su retiro al oratorio, siendo ya hombre de m\u00e1s de ochenta a\u00f1os y hall\u00e1ndose enfermo de hidropes\u00eda, se nos da a entender que vivi\u00f3 asistido por alg\u00fan presb\u00edtero; que dispuso de un caballejo, que en una ocasi\u00f3n le robaron, y que se rode\u00f3 de santas mujeres, v\u00edrgenes del Se\u00f1or, que le cuidaban en los \u00faltimos tiempos de su extrema ancianidad. Parece que al cumplir los cien a\u00f1os tuvo aviso de su pr\u00f3xima muerte y que al llegar la hora llam\u00f3 junto a s\u00ed al presb\u00edtero Aselo, que con \u00e9l viv\u00eda, y, confes\u00e1ndose con \u00e9l, entreg\u00f3 el alma a Dios.<\/p>\n<p style=\"text-align: justify;\">Se atribuyen a San Mill\u00e1n gran n\u00famero de milagros, que San Braulio refiere por lo menudo y Berceo reproduce, apoy\u00e1ndose en la tradici\u00f3n oral que transmiti\u00f3 hasta los nombres de las personas favorecidas. En realidad parece que la virtud milagrosa del Santo se ejerce principalmente en las curaciones de ciegos, tullidos y paral\u00edticos, que a \u00e9l acud\u00edan de todas partes, y en la expulsi\u00f3n de los demonios. A t\u00edtulo de curiosidad, y por ser, indudablemente, el m\u00e1s legendario de todos los milagros de San Mill\u00e1n, la mayor\u00eda de los cuales entran en el orden de los que Dios ha obrado muchas veces por el intermedio de los santos, referiremos que en cierta ocasi\u00f3n el demonio le sali\u00f3 al camino y le ret\u00f3 a medir sus fuerzas con \u00e9l, para lo cual tomar\u00eda el esp\u00edritu del mal forma y cuerpo tangibles. H\u00edzolo as\u00ed, pero sali\u00f3 malparado de la lucha, porque San Mill\u00e1n implor\u00f3 el socorro de los \u00e1ngeles, que le ayudaron a vencer. La leyenda medieval concreta en esta forma su admiraci\u00f3n por el poder\u00edo que el Santo tuvo sobre el demonio.<\/p>\n<p style=\"text-align: justify;\">La devoci\u00f3n a San Mill\u00e1n fue, evidentemente, muy viva en la alta Edad Media. Venerado entra\u00f1ablemente en la manera que descubre el propio estilo del texto de San Braulio, fue, a partir del siglo XVI, despu\u00e9s de la unidad espa\u00f1ola y de la existencia de una gram\u00e1tica castellana, objeto de ardientes controversias, nacidas de la interpretaci\u00f3n de los viejos c\u00f3dices latinos y atizadas por el af\u00e1n comarcal de apropiarse la pertenencia de un var\u00f3n tan ilustre. As\u00ed se consigui\u00f3 enturbiar el limpio arroyo de la tradici\u00f3n que Berceo hab\u00eda recogido y popularizado. Y eso que la autoridad de Gonzalo de Berceo en este caso debe valorarse en mucho por hallarse el poeta en el mismo punto de conjunci\u00f3n del lat\u00edn vulgar con el castellano reci\u00e9n nacido y ofrecer por eso la mayor garant\u00eda de autenticidad en su nomenclatura, que \u00e9l, por otra parte, no supone que pueda ponerse en tela de juicio.<\/p>\n<p style=\"text-align: justify;\">Una breve s\u00edntesis de las pol\u00e9micas servir\u00e1 para aclararle al lector esa geograf\u00eda de San Braulio, que ha de resultarle forzosamente oscura, con su Vergegio, con su Bilibio, con su monte Distercio&#8230; Recordemos que el Santo vive en el siglo VI y aun por una referencia de San Braulio puede colegirse que su muerte acaeci\u00f3 a no excesiva distancia del final del reinado de Leovigildo, lo cual, dada la longevidad del Santo, situar\u00eda su nacimiento en el \u00faltimo cuarto del siglo V. Las precisiones documentales que se poseen hoy sobre aquella \u00e9poca no son para darle alientos a ning\u00fan investigador.<\/p>\n<p style=\"text-align: justify;\">En primer lugar \u00bfa qu\u00e9 pueblo de hoy corresponde el Vergegio en que el Santo naci\u00f3? Lo \u00fanico que sabemos seguro es que pertenec\u00eda a la di\u00f3cesis de Tarazona. Para Gonzalo de Berceo no hay duda posible:<\/p>\n<p style=\"text-align: justify;\"><em>Cerca es de Cogolla de parte de Orient<\/em><br \/>\n<em>dos leguas sobre Nagera al pie de Sant Lorent <\/em><br \/>\n<em>el barrio de Berceo, Madriz la iaz present. <\/em><br \/>\n<em>Inaci\u00f3 Sant Millan, esto sin falliment.<\/em><\/p>\n<p style=\"text-align: justify;\">All\u00ed, en Berceo, naci\u00f3 San Mill\u00e1n, y sin duda alguna, lo que se corrobora m\u00e1s adelante en el poema, poni\u00e9ndolo en boca del mismo Santo:<\/p>\n<p style=\"text-align: justify;\"><em>En Berceo fui nado, cerca es de Madriz,<\/em><br \/>\n<em>Mill\u00f3n me puso nomne la mi buena nodriz.<\/em><\/p>\n<p style=\"text-align: justify;\">Madriz, ya se ha entendido, es un lugar inmediato a Berceo. Pero quieren algunos aragoneses recabar para su tierra el nacimiento de San Mill\u00e1n, para lo cual reciben muy buena ayuda en el tomo 50 de la <em>Espa\u00f1a <\/em>Sagrada, donde el historiador don Vicente de la Fuente arguye que Vergegio es Verdejo, lugar de Arag\u00f3n ya mencionado en el Fuero de Calatayud. Los argumentos de tipo ling\u00fc\u00edstico que parec\u00edan deponer en este caso a favor de Verdejo deponen, en realidad, a favor de Berceo, cuya afinidad con Vergegio es mucho m\u00e1s efectiva que la de Verdejo, tanto m\u00e1s cuanto que, remont\u00e1ndonos al mencionado <em>Fuero <\/em>de Calatayud, donde consta el nombre de Verdejo, lo vemos aparecer como Berdello, forma ya inadmisible como intermedia entre Vergegio y Verdejo. No olvidemos, por otra parte, que el padre Manuel Risco, en el tomo 33 de la Espa\u00f1a <em>Sagrada<\/em><em>, <\/em>al tratar de los santos del obispado de Calahorra, deja de lado a San Mill\u00e1n, pues aunque nacido en Vereco, de la di\u00f3cesis calagurritana \u00abdesde que los reyes de Navarra echaron los moros de toda esta provincia\u00bb, perteneci\u00f3 en los siglos anteriores a la di\u00f3cesis de Tarazona, como hall\u00e1ndose en territorio dela Celtiberia, \u00abla cual se extend\u00eda por los montes Idubedas, que en aquella parte se dijeron Distercios\u00bb.<\/p>\n<p style=\"text-align: justify;\">No pudo el padre Risco, porque se lo impidi\u00f3 la muerte, ocuparse de San Mill\u00e1n, pero la nota a la que nos hemos referido es muy importante y no alcanz\u00f3 don Vicente de la Fuentea refutarla. Puede darse por averiguado que Berceo perteneci\u00f3 a la di\u00f3cesis de Tarazona antes de pasar a depender de Calahorra. Por otra parte, los primeros pasos de San Mill\u00e1n tienen una l\u00f3gica mucho mayor si se considera que el Santo parte de Berceo y no de Verdejo. Se dirige, como nos ha dicho San Braulio, al castillo de Bilibio. \u00bfD\u00f3nde est\u00e1 Bilibio? Atrevidamente se quiso en el siglo XVI suponer que Bilibio pudiera ser Bilbilio, con lo cual se le asimilaba a B\u00edlbilis (Calatayud). Pero esta forzad\u00edsima interpretaci\u00f3n ha sido desechada un\u00e1nimemente y se conviene por todos en que Bilibio estaba en las proximidades de la actual ciudad de Haro, en la Rioja. <em>Bilibium<\/em><em>, <\/em>seg\u00fan el padre Risco, es probable corrupci\u00f3n de <em>Bilabium, <\/em>dos labios o escarpaduras entre las cuales irrump\u00eda el Ebro en tierra riojana, lugar estrat\u00e9gico para emplazar un fuerte castillo. Que el joven pastor, tocado por la gracia, se dirigiese de Berceo a Haro es mucho m\u00e1s l\u00f3gico que lo hiciese desde Verdejo, y a esto s\u00f3lo se replica que a veces los anacoretas marchaban a pa\u00edses muy lejanos. Pero San Mill\u00e1n no iba, como si dij\u00e9ramos, a instalarse, sino a instruirse, atra\u00eddo por la fama de un monje, que hab\u00eda llegado a sus o\u00eddos por morar en paraje no lejano del suyo m\u00e1s de unas cuatro leguas.<\/p>\n<p style=\"text-align: justify;\">No tendr\u00edamos, pues, discusi\u00f3n sino en cuanto al lugar de nacimiento; pero no en cuanto al verdadero escenario de la vida de San Mill\u00e1n. Sin embargo, a\u00fan queda sobre esto algo que decir. Los partidarios de Verdejo pierden mucho cuando resulta forzoso convenir que el monte Distercio\u2014y en esto todos est\u00e1n conformes\u2014, donde San Mill\u00e1n pas\u00f3 los cuarenta a\u00f1os de su vida de anacoreta; no es otro que el monte, o sierra m\u00e1s bien, dela Cogolla, de donde le viene a San Mill\u00e1n su usual apellido. Como San Mill\u00e1n volvi\u00f3 a las cercan\u00edas de su pueblo, seg\u00fan indica San Braulio, despu\u00e9s del tiempo que permaneci\u00f3 con el monje Felices, y al verse all\u00ed acosado de la gente se retir\u00f3 a lo m\u00e1s elevado e intrincado del Distercio (la Cogolla), este proceso de traslaci\u00f3n resulta f\u00e1cil y l\u00f3gico teniendo a Berceo como centro y no es igualmente explicable partiendo de Verdejo. Lo que verdaderamente otorga a Berceo sus mayores probabilidades, aparte de m\u00faltiples testimonios de la tradici\u00f3n, es el haberse identificado a Bilibio en las cercan\u00edas de Haro y al Distercio enla Cogolla. Tambi\u00e9npartiendo de Verdejo resulta inexplicable el \u00faltimo retiro de San Mill\u00e1n, depuesto del curato, pues lo m\u00e1s seguro parece que el que San Braulio llama \u00aboratorio\u00bb del Santo estuviese en el emplazamiento del monasterio de Suso.<\/p>\n<p style=\"text-align: justify;\">Se admite corrientemente que San Mill\u00e1n muri\u00f3 en el a\u00f1o 574. Poni\u00e9ndose muy en duda, sin embargo, la fuente principal de donde pudiera deducirse aquella fecha, y s\u00f3lo queda en pie la referencia de San Braulio en la relaci\u00f3n de milagros, cuando dice que profetiz\u00f3 la destrucci\u00f3n de Cantabria, o sea la acci\u00f3n punitiva de Leovigildo en esta regi\u00f3n, un a\u00f1o antes de que acaeciese, con lo cual, computando fechas, viene a darse en la de 574 como probable data de la muerte. Esta misma fecha, cifrada a lo g\u00f3tico, consta en cierto epitafio descubierto en 1601, cuando el abad de San Mill\u00e1n ascendi\u00f3 al monasterio de Suso para reconocer la tumba del Santo, y al no poder levantar el cantero la piedra que cubr\u00eda el sepulcro, abri\u00f3 uno de los costados y qued\u00f3 de manifiesto una l\u00e1pida que ser\u00eda un tesoro si su autenticidad no se hubiera puesto tan en duda. Porque all\u00ed no s\u00f3lo consta la referida fecha, sino que San Mill\u00e1n fue monje dela Ordende San Benito y era abad cuando descans\u00f3 en el Se\u00f1or.<\/p>\n<p style=\"text-align: justify;\">Que se trate de una piadosa, aunque reprobable, supercher\u00eda de los monjes, que de este modo recaban a San Mill\u00e1n entero para s\u00ed, o que, sin mediar supercher\u00eda alguna, sea un epitafio en extremo posterior, como ha de serlo a la fecha de la muerte y se haya recogido all\u00ed lo que tradicionalmente se afirmaba, es cuesti\u00f3n que no importa demasiado. La teor\u00eda de la falsificaci\u00f3n pura y simple tiene sus partidarios, que argumentan con el traslado de los restos, realizado por Sancho el Mayor de Navarra en 1030, el cual habr\u00eda tenido que dejar el epitafio all\u00ed. Esto, seg\u00fan otros, pudo ser intencionado, ya que en el sepulcro quedaban cenizas, reliquias tambi\u00e9n, que le confer\u00edan al sepulcro venerable car\u00e1cter. En todo caso, se discute asimismo la calidad ap\u00f3crifa de la inscripci\u00f3n, que se considera de un g\u00f3tico extremadamente dudoso.<\/p>\n<p style=\"text-align: justify;\">Queda en pie de toda esta pol\u00e9mica la cuesti\u00f3n de si efectivamente San Mill\u00e1n fue abad dela Ordenbenedictina. Seguir la discusi\u00f3n entablada desde el siglo XVI sobre este punto resultar\u00eda harto prolijo. Aun el mismo hecho de las santas mujeres que atend\u00edan y cuidaban a San Mill\u00e1n en lo m\u00e1s desvalido de su ancianidad extrema, que algunos estiman de todo punto incompatible con el monacato, tiene su explicaci\u00f3n plausible para quienes lo defienden. Hemos de tener presentes las condiciones excepcionales en las que se desenvolv\u00eda la vida religiosa y mon\u00e1stica en el siglo VI, aunque tambi\u00e9n debe tenerse en cuenta que la \u00fanica fuente biogr\u00e1fica de autoridad que poseemos, que es el relato de San Braulio, no hace la menor alusi\u00f3n a que San Mill\u00e1n fuese abad, y aun es dudoso que le considere monje, si bien el no designarle as\u00ed concretamente se ha de entender ocioso, pues monje fue no s\u00f3lo en el sentido etimol\u00f3gico de la palabra, sino en el de la obediencia (a m\u00e1s de pobreza y castidad), que se prob\u00f3 cuando el obispo de Tarazona le reclam\u00f3 para que recibiese las sagradas \u00f3rdenes, lo que no hubiera podido obligar a un simple diocesano.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/San-Mill\u00e1n.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1086\" src=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/San-Mill\u00e1n.png\" alt=\"\" width=\"314\" height=\"188\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Basta con dejar apuntada esta cuesti\u00f3n. Sobre la trayectoria seguida por los restos del Santo, una bella leyenda les se\u00f1ala el emplazamiento de la morada final. Ya hemos dicho que en 1030, Sancho el Mayor los traslad\u00f3 desde el \u00aboratorio\u00bb, monasterio de Suso, al altar mayor, donde permanecieron hasta el 1053, en el que don Garc\u00eda, hijo de don Sancho, los quiso trasladar al monasterio de N\u00e1jera. Pero colocado el ata\u00fad en un carro de bueyes, no hubo medio humano de que el carro se moviese de determinado lugar, donde qued\u00f3 como clavado a la tierra, dando indicio cierto de que una voluntad superior se opon\u00eda a que pasase de all\u00ed. Y all\u00ed fue donde el rey dispuso que se levantara un nuevo monasterio con el nombre del Santo, en el que sus restos descansaran en espl\u00e9ndida sepultura, en la que, para la urna sepulcral, se derroch\u00f3 el marfil, el oro y la pedrer\u00eda. Tres razones m\u00e1s que suficientes para que los restos del Santo fueran inquietados en 1809, cuando la francesada despleg\u00f3 por all\u00ed su esp\u00edritu rapaz.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0Texto de D.<\/em> <em>Nicol\u00e1s Gonz\u00e1lez Ruiz escritor, cr\u00edtico literario y periodista (Matar\u00f3, 1897 &#8211; Madrid, 1967). Ense\u00f1\u00f3 Lengua y Literatura espa\u00f1ola en la Universidad de Liverpool (1921-22). En 1923 ingres\u00f3 en <\/em><em>El Debate<\/em><em>, de Madrid y desde 1939 fue editorialista del peri\u00f3dico <\/em><em>Ya<\/em><em>, de Madrid. Fue galardonado con el premio Luca de Tena (1948) y nombrado periodista de honor (1956). En 1961 fue nombrado director de la Escuela de Periodismo de la Iglesia. Public\u00f3: <\/em><em>El precio de la victoria<\/em><em>, comedia dram\u00e1tica; las vidas paralelas de <\/em><em>Mar\u00eda Estuardo y Mar\u00eda Antonieta<\/em><em> y de <\/em><em>Mar\u00eda Luisa y Catalina la Grande<\/em><em>, la biograf\u00eda de Herv\u00e1s y Panduro, <\/em><em>La Literatura<\/em><em> espa\u00f1ola<\/em><em> (1898-1936), <\/em><em>El regreso de las sombras<\/em><em> (1952), <\/em><em>Obra selecta<\/em><em> (1958), <\/em><em>Genio y figura del padre Pulgar <\/em><em>(1961), <\/em><em>La Caramba<\/em><em>, <\/em><em>Santa Isabel de Hungr\u00eda<\/em><em>, <\/em><em>Axel de Fersen<\/em><em>, <\/em><em>El rom\u00e1ntico amor de Mar\u00eda Antonieta <\/em><em>y <\/em><em>El teatro teol\u00f3gico espa\u00f1ol<\/em><em>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN MILL\u00c1N DE LA COGOLLA La Iglesia conmemora hoy 12 de noviembre, la festividad de San Mill\u00e1n, santo totalmente relacionado con nuestra tierra y nuestra Di\u00f3cesis.\u00a0Hemos\u00a0encontrado este gran trabajo de D. Nicol\u00e1s Gonz\u00e1lez Ru\u00edz, donde queda bien detallada y comprobada, la vida de nuestro santo, y los trayectos efectuados durante su larga vida. Para contar sencillamente la vida de San Mill\u00e1n disponemos de un testimonio fidedigno, sin que esto quiera decir que no deba somet\u00e9rsele por ello al an\u00e1lisis de la cr\u00edtica hist\u00f3rica. San Braulio, obispo de Zaragoza, nos leg\u00f3 un op\u00fasculo latino en el que relata la vida de&hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_crdt_document":"","footnotes":""},"categories":[3,1,4],"tags":[],"class_list":["post-1082","post","type-post","status-publish","format-standard","hentry","category-iglesia","category-noticias","category-sabias-que"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Millan de la Cogolla - Logro\u00f1o Pasi\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Millan de la Cogolla - Logro\u00f1o Pasi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"SAN MILL\u00c1N DE LA COGOLLA La Iglesia conmemora hoy 12 de noviembre, la festividad de San Mill\u00e1n, santo totalmente relacionado con nuestra tierra y nuestra Di\u00f3cesis.\u00a0Hemos\u00a0encontrado este gran trabajo de D. Nicol\u00e1s Gonz\u00e1lez Ru\u00edz, donde queda bien detallada y comprobada, la vida de nuestro santo, y los trayectos efectuados durante su larga vida. Para contar sencillamente la vida de San Mill\u00e1n disponemos de un testimonio fidedigno, sin que esto quiera decir que no deba somet\u00e9rsele por ello al an\u00e1lisis de la cr\u00edtica hist\u00f3rica. San Braulio, obispo de Zaragoza, nos leg\u00f3 un op\u00fasculo latino en el que relata la vida de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/\" \/>\n<meta property=\"og:site_name\" content=\"Logro\u00f1o Pasi\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/logronopasion\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-12T09:35:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-26T18:55:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png\" \/>\n<meta name=\"author\" content=\"ROU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LogronoPasion\" \/>\n<meta name=\"twitter:site\" content=\"@LogronoPasion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ROU\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/\"},\"author\":{\"name\":\"ROU\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/person\\\/2f883c3fdb92c04e9616af63b5dcfcf2\"},\"headline\":\"San Millan de la Cogolla\",\"datePublished\":\"2012-11-12T09:35:18+00:00\",\"dateModified\":\"2012-11-26T18:55:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/\"},\"wordCount\":3865,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/cruzSanmillan.png\",\"articleSection\":[\"Iglesia - estado, sociedad y religi\u00f3n\",\"Noticias \\\/ Actualidad\",\"\u00bfSab\u00edas que...? derechos y deberes de los cristianos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/\",\"name\":\"San Millan de la Cogolla - Logro\u00f1o Pasi\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/cruzSanmillan.png\",\"datePublished\":\"2012-11-12T09:35:18+00:00\",\"dateModified\":\"2012-11-26T18:55:14+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/san-millan-de-la-cogolla\\\/#primaryimage\",\"url\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/cruzSanmillan.png\",\"contentUrl\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/cruzSanmillan.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/\",\"name\":\"Logro\u00f1o Pasi\u00f3n\",\"description\":\"Portal sobre la Semana Santa de Logro\u00f1o\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#organization\",\"name\":\"Logro\u00f1o Pasi\u00f3n\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/cropped-Header-1.jpg?fit=312%2C212&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/cropped-Header-1.jpg?fit=312%2C212&ssl=1\",\"width\":312,\"height\":212,\"caption\":\"Logro\u00f1o Pasi\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/logronopasion\",\"https:\\\/\\\/x.com\\\/LogronoPasion\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/person\\\/2f883c3fdb92c04e9616af63b5dcfcf2\",\"name\":\"ROU\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/16107_209547569181270_194186917_n-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/16107_209547569181270_194186917_n-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/16107_209547569181270_194186917_n-1-150x150.jpg\",\"caption\":\"ROU\"},\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/author\\\/rou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Millan de la Cogolla - Logro\u00f1o Pasi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/","og_locale":"es_ES","og_type":"article","og_title":"San Millan de la Cogolla - Logro\u00f1o Pasi\u00f3n","og_description":"SAN MILL\u00c1N DE LA COGOLLA La Iglesia conmemora hoy 12 de noviembre, la festividad de San Mill\u00e1n, santo totalmente relacionado con nuestra tierra y nuestra Di\u00f3cesis.\u00a0Hemos\u00a0encontrado este gran trabajo de D. Nicol\u00e1s Gonz\u00e1lez Ru\u00edz, donde queda bien detallada y comprobada, la vida de nuestro santo, y los trayectos efectuados durante su larga vida. Para contar sencillamente la vida de San Mill\u00e1n disponemos de un testimonio fidedigno, sin que esto quiera decir que no deba somet\u00e9rsele por ello al an\u00e1lisis de la cr\u00edtica hist\u00f3rica. San Braulio, obispo de Zaragoza, nos leg\u00f3 un op\u00fasculo latino en el que relata la vida de&hellip;","og_url":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/","og_site_name":"Logro\u00f1o Pasi\u00f3n","article_publisher":"https:\/\/www.facebook.com\/logronopasion","article_published_time":"2012-11-12T09:35:18+00:00","article_modified_time":"2012-11-26T18:55:14+00:00","og_image":[{"url":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png","type":"","width":"","height":""}],"author":"ROU","twitter_card":"summary_large_image","twitter_creator":"@LogronoPasion","twitter_site":"@LogronoPasion","twitter_misc":{"Escrito por":"ROU","Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/#article","isPartOf":{"@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/"},"author":{"name":"ROU","@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/person\/2f883c3fdb92c04e9616af63b5dcfcf2"},"headline":"San Millan de la Cogolla","datePublished":"2012-11-12T09:35:18+00:00","dateModified":"2012-11-26T18:55:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/"},"wordCount":3865,"commentCount":0,"publisher":{"@id":"https:\/\/www.logronopasion.com\/portal\/#organization"},"image":{"@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/#primaryimage"},"thumbnailUrl":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png","articleSection":["Iglesia - estado, sociedad y religi\u00f3n","Noticias \/ Actualidad","\u00bfSab\u00edas que...? derechos y deberes de los cristianos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/","url":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/","name":"San Millan de la Cogolla - Logro\u00f1o Pasi\u00f3n","isPartOf":{"@id":"https:\/\/www.logronopasion.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/#primaryimage"},"image":{"@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/#primaryimage"},"thumbnailUrl":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png","datePublished":"2012-11-12T09:35:18+00:00","dateModified":"2012-11-26T18:55:14+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logronopasion.com\/portal\/san-millan-de-la-cogolla\/#primaryimage","url":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png","contentUrl":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/11\/cruzSanmillan.png"},{"@type":"WebSite","@id":"https:\/\/www.logronopasion.com\/portal\/#website","url":"https:\/\/www.logronopasion.com\/portal\/","name":"Logro\u00f1o Pasi\u00f3n","description":"Portal sobre la Semana Santa de Logro\u00f1o","publisher":{"@id":"https:\/\/www.logronopasion.com\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.logronopasion.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.logronopasion.com\/portal\/#organization","name":"Logro\u00f1o Pasi\u00f3n","url":"https:\/\/www.logronopasion.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/logronopasion.com\/portal\/wp-content\/uploads\/2019\/04\/cropped-Header-1.jpg?fit=312%2C212&ssl=1","contentUrl":"https:\/\/i2.wp.com\/logronopasion.com\/portal\/wp-content\/uploads\/2019\/04\/cropped-Header-1.jpg?fit=312%2C212&ssl=1","width":312,"height":212,"caption":"Logro\u00f1o Pasi\u00f3n"},"image":{"@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/logronopasion","https:\/\/x.com\/LogronoPasion"]},{"@type":"Person","@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/person\/2f883c3fdb92c04e9616af63b5dcfcf2","name":"ROU","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logronopasion.com\/portal\/wp-content\/uploads\/2021\/11\/16107_209547569181270_194186917_n-1-150x150.jpg","url":"https:\/\/www.logronopasion.com\/portal\/wp-content\/uploads\/2021\/11\/16107_209547569181270_194186917_n-1-150x150.jpg","contentUrl":"https:\/\/www.logronopasion.com\/portal\/wp-content\/uploads\/2021\/11\/16107_209547569181270_194186917_n-1-150x150.jpg","caption":"ROU"},"url":"https:\/\/www.logronopasion.com\/portal\/author\/rou\/"}]}},"_links":{"self":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts\/1082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/comments?post=1082"}],"version-history":[{"count":11,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts\/1082\/revisions"}],"predecessor-version":[{"id":1191,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts\/1082\/revisions\/1191"}],"wp:attachment":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/media?parent=1082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/categories?post=1082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/tags?post=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}