{"id":1262,"date":"2012-12-12T14:15:49","date_gmt":"2012-12-12T14:15:49","guid":{"rendered":"http:\/\/logronopasion.com\/portal\/?p=1262"},"modified":"2012-12-12T14:15:49","modified_gmt":"2012-12-12T14:15:49","slug":"peticion-de-d-juan-jose-omella-omella","status":"publish","type":"post","link":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/","title":{"rendered":"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella"},"content":{"rendered":"<figure id=\"attachment_1264\" aria-describedby=\"caption-attachment-1264\" style=\"width: 390px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1264\" src=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg\" alt=\"D. Juan Jos\u00e9 Omella Omella\" width=\"390\" height=\"180\" srcset=\"https:\/\/www.logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg 390w, https:\/\/www.logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801-300x138.jpg 300w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/a><figcaption id=\"caption-attachment-1264\" class=\"wp-caption-text\">D. Juan Jos\u00e9 Omella Omella<\/figcaption><\/figure>\n<p>El obispo de la Di\u00f3cesis riojana, D. Juan Jos\u00e9 Omella Omella, ha animado a todas las personas a donar la paga extraordinaria de Navidad a los m\u00e1s necesitados como consecuencia de la crisis econ\u00f3mica y a continuar con la aportaci\u00f3n del 10 por ciento de su sueldo, lo que ya propuso hace tres a\u00f1os.<\/p>\n<p>Nuestro Obispo, en una carta sobre el compromiso ante la crisis econ\u00f3mica, ha apelado a los sacerdotes, congregaciones, organismos religiosos, colegios cat\u00f3licos, parroquias, parroquias, movimientos y grupos apost\u00f3licos y a los hombres y mujeres de buena voluntad, a todos, para que donen su paga extraordinaria del mes de diciembre.<\/p>\n<p>D. Juan Jos\u00e9 Omella Omella, obispo de Calahorra y La Calzada-Logro\u00f1o, para paliar el efecto de la crisis, ya impuls\u00f3 en 2009, el \u00abFondo Crisis\u00bb o \u00abFondo de Solidaridad\u00bb, en su empe\u00f1o por atender a los m\u00e1s necesitados.<\/p>\n<p>El objetivo de este fondo, que ya ha recaudado 292.950 euros y ha atendido a 155 familias sin recursos alguno, es dar subsidios, ayudas y crear becas de trabajo, en la Fundaci\u00f3n C\u00e1ritas Chavicar o de otra manera, para parados sin ning\u00fan tipo de ayuda y sin ning\u00fan ingreso familiar. Este fondo se nutre de aportaciones especiales de los sacerdotes con la entrega del 10 por ciento del sueldo durante un a\u00f1o o una paga extraordinaria, as\u00ed como de otras procedentes de congregaciones y organismos religiosos, colegios cat\u00f3licos, parroquias, movimientos y grupos apost\u00f3licos y de donativos expresos de los fieles para este fin.<\/p>\n<p>Tambi\u00e9n ha invitado a revisar los gastos ordinarios y extraordinarios en estas fechas, tanto en organismos oficiales, casas particulares y de las instituciones eclesiales desde una \u00f3ptica de mayor austeridad \u00a0y sentido solidario.<\/p>\n<p>A\u00f1o tras a\u00f1o, y ya van tres, ha repetido esta petici\u00f3n de ayuda ante la delicada situaci\u00f3n de muchas personas, ya que la situaci\u00f3n ha empeorado para muchos ciudadanos por el aumento del paro.<\/p>\n<p>\u00abNo se puede esconder la cabeza frente a lo que est\u00e1 ocurriendo ni, mucho menos, mirar para otro lado frente al sufrimiento de tantas personas\u00bb, ha precisado nuestro Sr, Obispo, quien cree que cada uno debe ejercitar la solidaridad dentro de sus posibilidades con quienes sufren las consecuencias de la crisis.<\/p>\n<p>Por ello, ha invitado a reaccionar ante esta situaci\u00f3n y a tratar de ayudar con lo poco o lo mucho que cada uno tenga y ha apelado a seguir potenciando seriamente las estructuras y el funcionamiento de C\u00e1ritas en toda la Di\u00f3cesis.<\/p>\n<p>Para D. Juan Jos\u00e9, actuar coordinadamente y tener una organizaci\u00f3n que funcione bien, con equipos de personas cercanos y sensibles a los problemas, es lo permite que en los momentos de especial dificultad, como el actual, se puedan dar respuestas oportunas y significativas a las necesidades de los \u00ab\u00faltimos\u00bb de la sociedad. El llamado Fondo Crisis ser\u00e1 \u00f3 es una gota en el oc\u00e9ano de la pobreza, pero es una gota que ha dado \u00e1nimo y esperanza a esas familias tan necesitadas.<\/p>\n<p>Los datos indican que dicho fondo, durante los \u00faltimos tres a\u00f1os, ha recibido la solicitud de 180 personas, de los que 128, un 71 por ciento, eran extranjeros y 52, un 29 por ciento, eran espa\u00f1oles y, hasta ahora, 166 casos han obtenido respuesta y hay 14 casos nuevos pendientes de ser valorados.<\/p>\n<p>Miembros de C\u00e1ritas realizan un seguimiento individualizado de la situaci\u00f3n de cada uno y concede una ayuda econ\u00f3mica de 400 euros al mes y, en aquellos casos en los que es posible, una ayuda suplementaria de formaci\u00f3n.<\/p>\n<p>Un 60 por ciento de los planes formativos se ha realizado en la Fundaci\u00f3n C\u00e1ritas Chavicar y un 36 por ciento ha sido con planes individuales parroquiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El obispo de la Di\u00f3cesis riojana, D. Juan Jos\u00e9 Omella Omella, ha animado a todas las personas a donar la paga extraordinaria de Navidad a los m\u00e1s necesitados como consecuencia de la crisis econ\u00f3mica y a continuar con la aportaci\u00f3n del 10 por ciento de su sueldo, lo que ya propuso hace tres a\u00f1os. Nuestro Obispo, en una carta sobre el compromiso ante la crisis econ\u00f3mica, ha apelado a los sacerdotes, congregaciones, organismos religiosos, colegios cat\u00f3licos, parroquias, parroquias, movimientos y grupos apost\u00f3licos y a los hombres y mujeres de buena voluntad, a todos, para que donen su paga extraordinaria del&hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5,3,1,4],"tags":[],"class_list":["post-1262","post","type-post","status-publish","format-standard","hentry","category-criterios-morales","category-iglesia","category-noticias","category-sabias-que"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella - Logro\u00f1o Pasi\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella - Logro\u00f1o Pasi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El obispo de la Di\u00f3cesis riojana, D. Juan Jos\u00e9 Omella Omella, ha animado a todas las personas a donar la paga extraordinaria de Navidad a los m\u00e1s necesitados como consecuencia de la crisis econ\u00f3mica y a continuar con la aportaci\u00f3n del 10 por ciento de su sueldo, lo que ya propuso hace tres a\u00f1os. Nuestro Obispo, en una carta sobre el compromiso ante la crisis econ\u00f3mica, ha apelado a los sacerdotes, congregaciones, organismos religiosos, colegios cat\u00f3licos, parroquias, parroquias, movimientos y grupos apost\u00f3licos y a los hombres y mujeres de buena voluntad, a todos, para que donen su paga extraordinaria del&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/\" \/>\n<meta property=\"og:site_name\" content=\"Logro\u00f1o Pasi\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/logronopasion\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-12T14:15:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg\" \/>\n<meta name=\"author\" content=\"ROU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LogronoPasion\" \/>\n<meta name=\"twitter:site\" content=\"@LogronoPasion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ROU\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/\"},\"author\":{\"name\":\"ROU\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/person\\\/2f883c3fdb92c04e9616af63b5dcfcf2\"},\"headline\":\"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella\",\"datePublished\":\"2012-12-12T14:15:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/\"},\"wordCount\":644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/obipso-peticion-390x1801.jpg\",\"articleSection\":[\"Criterios morales de fondo\",\"Iglesia - estado, sociedad y religi\u00f3n\",\"Noticias \\\/ Actualidad\",\"\u00bfSab\u00edas que...? derechos y deberes de los cristianos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/\",\"name\":\"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella - Logro\u00f1o Pasi\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/obipso-peticion-390x1801.jpg\",\"datePublished\":\"2012-12-12T14:15:49+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/peticion-de-d-juan-jose-omella-omella\\\/#primaryimage\",\"url\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/obipso-peticion-390x1801.jpg\",\"contentUrl\":\"http:\\\/\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/obipso-peticion-390x1801.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/\",\"name\":\"Logro\u00f1o Pasi\u00f3n\",\"description\":\"Portal sobre la Semana Santa de Logro\u00f1o\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#organization\",\"name\":\"Logro\u00f1o Pasi\u00f3n\",\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/cropped-Header-1.jpg?fit=312%2C212&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/logronopasion.com\\\/portal\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/cropped-Header-1.jpg?fit=312%2C212&ssl=1\",\"width\":312,\"height\":212,\"caption\":\"Logro\u00f1o Pasi\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/logronopasion\",\"https:\\\/\\\/x.com\\\/LogronoPasion\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/#\\\/schema\\\/person\\\/2f883c3fdb92c04e9616af63b5dcfcf2\",\"name\":\"ROU\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2399a46c5538776f20b14a9ec7fa59675437eae61dec234f3a7031c25bf4152a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2399a46c5538776f20b14a9ec7fa59675437eae61dec234f3a7031c25bf4152a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2399a46c5538776f20b14a9ec7fa59675437eae61dec234f3a7031c25bf4152a?s=96&d=mm&r=g\",\"caption\":\"ROU\"},\"url\":\"https:\\\/\\\/www.logronopasion.com\\\/portal\\\/author\\\/rou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella - Logro\u00f1o Pasi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/","og_locale":"es_ES","og_type":"article","og_title":"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella - Logro\u00f1o Pasi\u00f3n","og_description":"El obispo de la Di\u00f3cesis riojana, D. Juan Jos\u00e9 Omella Omella, ha animado a todas las personas a donar la paga extraordinaria de Navidad a los m\u00e1s necesitados como consecuencia de la crisis econ\u00f3mica y a continuar con la aportaci\u00f3n del 10 por ciento de su sueldo, lo que ya propuso hace tres a\u00f1os. Nuestro Obispo, en una carta sobre el compromiso ante la crisis econ\u00f3mica, ha apelado a los sacerdotes, congregaciones, organismos religiosos, colegios cat\u00f3licos, parroquias, parroquias, movimientos y grupos apost\u00f3licos y a los hombres y mujeres de buena voluntad, a todos, para que donen su paga extraordinaria del&hellip;","og_url":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/","og_site_name":"Logro\u00f1o Pasi\u00f3n","article_publisher":"https:\/\/www.facebook.com\/logronopasion","article_published_time":"2012-12-12T14:15:49+00:00","og_image":[{"url":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg","type":"","width":"","height":""}],"author":"ROU","twitter_card":"summary_large_image","twitter_creator":"@LogronoPasion","twitter_site":"@LogronoPasion","twitter_misc":{"Escrito por":"ROU","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/#article","isPartOf":{"@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/"},"author":{"name":"ROU","@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/person\/2f883c3fdb92c04e9616af63b5dcfcf2"},"headline":"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella","datePublished":"2012-12-12T14:15:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/"},"wordCount":644,"commentCount":0,"publisher":{"@id":"https:\/\/www.logronopasion.com\/portal\/#organization"},"image":{"@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/#primaryimage"},"thumbnailUrl":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg","articleSection":["Criterios morales de fondo","Iglesia - estado, sociedad y religi\u00f3n","Noticias \/ Actualidad","\u00bfSab\u00edas que...? derechos y deberes de los cristianos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/","url":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/","name":"Petici\u00f3n de D. Juan Jos\u00e9 Omella Omella - Logro\u00f1o Pasi\u00f3n","isPartOf":{"@id":"https:\/\/www.logronopasion.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/#primaryimage"},"image":{"@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/#primaryimage"},"thumbnailUrl":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg","datePublished":"2012-12-12T14:15:49+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logronopasion.com\/portal\/peticion-de-d-juan-jose-omella-omella\/#primaryimage","url":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg","contentUrl":"http:\/\/logronopasion.com\/portal\/wp-content\/uploads\/2012\/12\/obipso-peticion-390x1801.jpg"},{"@type":"WebSite","@id":"https:\/\/www.logronopasion.com\/portal\/#website","url":"https:\/\/www.logronopasion.com\/portal\/","name":"Logro\u00f1o Pasi\u00f3n","description":"Portal sobre la Semana Santa de Logro\u00f1o","publisher":{"@id":"https:\/\/www.logronopasion.com\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.logronopasion.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.logronopasion.com\/portal\/#organization","name":"Logro\u00f1o Pasi\u00f3n","url":"https:\/\/www.logronopasion.com\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/logronopasion.com\/portal\/wp-content\/uploads\/2019\/04\/cropped-Header-1.jpg?fit=312%2C212&ssl=1","contentUrl":"https:\/\/i2.wp.com\/logronopasion.com\/portal\/wp-content\/uploads\/2019\/04\/cropped-Header-1.jpg?fit=312%2C212&ssl=1","width":312,"height":212,"caption":"Logro\u00f1o Pasi\u00f3n"},"image":{"@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/logronopasion","https:\/\/x.com\/LogronoPasion"]},{"@type":"Person","@id":"https:\/\/www.logronopasion.com\/portal\/#\/schema\/person\/2f883c3fdb92c04e9616af63b5dcfcf2","name":"ROU","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2399a46c5538776f20b14a9ec7fa59675437eae61dec234f3a7031c25bf4152a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2399a46c5538776f20b14a9ec7fa59675437eae61dec234f3a7031c25bf4152a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2399a46c5538776f20b14a9ec7fa59675437eae61dec234f3a7031c25bf4152a?s=96&d=mm&r=g","caption":"ROU"},"url":"https:\/\/www.logronopasion.com\/portal\/author\/rou\/"}]}},"_links":{"self":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts\/1262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/comments?post=1262"}],"version-history":[{"count":2,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts\/1262\/revisions"}],"predecessor-version":[{"id":1266,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/posts\/1262\/revisions\/1266"}],"wp:attachment":[{"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/media?parent=1262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/categories?post=1262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.logronopasion.com\/portal\/wp-json\/wp\/v2\/tags?post=1262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}